{"id":55908,"date":"2025-08-10T23:13:01","date_gmt":"2025-08-10T15:13:01","guid":{"rendered":"https:\/\/massagetaipei.com\/?page_id=55908"},"modified":"2026-08-03T18:04:13","modified_gmt":"2026-08-03T10:04:13","slug":"%e8%9c%9c%e6%9c%88%e6%9c%9f","status":"publish","type":"page","link":"https:\/\/massagetaipei.com\/012\/%e8%9c%9c%e6%9c%88%e6%9c%9f\/","title":{"rendered":"\u871c\u6708\u671f"},"content":{"rendered":"<p>\u871c\u6708\u671f(\u2b55\ufe0f\u53ef\u5237\u5361 \u52a0\u6536\u624b\u7e8c\u8cbb10%)<\/p>\n<p>\u2605\u7531\u65bc\u7f8e\u5bb9\u5e2b\u53ef\u80fd\u81e8\u6642\u8acb\u5047\u6216\u52a0\u73ed\uff0c\u8a73\u7d30\u5230\u73ed\u60c5\u6cc1\u8acbline\u79c1\u8a0a\u8a62\u554f\u70ba\u4e3b\u2605<\/p>\n<p>\u4f11\u9928\u4e2d~<\/p>\n<p>\u6d88\u8cbb\u6642\u9593\uff1a60\u5206\u9418\u70ba\u4e00\u7bc0<br \/>\n\u50f9\u683c\u4f9d\u7167\u7f8e\u5bb9\u5e2b\u7d20\u8cea\u6703\u6709\u4e9b\u5fae\u5dee\u7570<br \/>\n\u4e00\u5f8b\u4ee5\u73ed\u8868\u4e0a\u3010\u55ae\u50f9\u3011\u6b04\u4f4d\u6240\u6a19\u793a\u7684\u724c\u50f9\u70ba\u6e96<\/p>\n<p>\u7bc4\u4f8b\uff1a<br \/>\n\u55ae\u50f9\u6b04\u4f4d\u6a19\u793a\u70ba\u301023\u3011\uff0c\u5373\u662f60\u5206\u9418$2300<\/p>\n<p>\u2728\u53e6\u52a0\u6536\u5305\u5ec2\u8cbb100<\/p>\n<p>\u6e05\u6f54\u8cbb\uff1a\u6709\u52a0\u503c\u53e6\u52a0\u6536 \u97f3\u6a02200 \u9ad4\u80b2200<\/p>\n<p>\u5730\u5740\uff1a<\/p>\n<p>\u3010\u4e2d\u5c71\u5340\u3011\uff0c&lt;\u8fd1\u6c11\u751f\u6771\u8def&gt;\u6377\u904b\u5584\u5c0e\u5bfa\u7ad9<\/p>\n<p>\u71df\u696d\u6642\u9593\uff1a<\/p>\n<p>\u4e2d\u534812\uff1a00\u301c\u9694\u65e5\u65e9\u4e0a06:00\uff08\u65e9\u4e0a05:00\u6700\u5f8c\u6536\u5ba2\uff09<\/p>\n<p>\u6709\u95dc\u82b3\u7642\u5e2b\u5230\u73ed\u7684\u8a73\u7d30\u72c0\u6cc1\uff0c\u53ef\u4ee5\u767c\u7dda\u8a62\u554f\u6211\u5011\uff0c\u4ee5\u9632\u8cb4\u8cd3\u5011\u767d\u8dd1\u4e00\u8d9f\u5537<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>\u871c\u6708\u671f(\u2b55\ufe0f\u53ef\u5237\u5361 \u52a0\u6536\u624b\u7e8c\u8cbb10%) \u2605\u7531\u65bc\u7f8e\u5bb9\u5e2b\u53ef\u80fd\u81e8\u6642\u8acb\u5047\u6216\u52a0\u73ed\uff0c\u8a73\u7d30\u5230\u73ed\u60c5\u6cc1\u8acbline\u79c1\u8a0a\u8a62\u554f\u70ba\u4e3b\u2605  &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/massagetaipei.com\/012\/%e8%9c%9c%e6%9c%88%e6%9c%9f\/\"> <span class=\"screen-reader-text\">\u871c\u6708\u671f<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-55908","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/massagetaipei.com\/012\/wp-json\/wp\/v2\/pages\/55908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massagetaipei.com\/012\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/massagetaipei.com\/012\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/massagetaipei.com\/012\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/massagetaipei.com\/012\/wp-json\/wp\/v2\/comments?post=55908"}],"version-history":[{"count":0,"href":"https:\/\/massagetaipei.com\/012\/wp-json\/wp\/v2\/pages\/55908\/revisions"}],"wp:attachment":[{"href":"https:\/\/massagetaipei.com\/012\/wp-json\/wp\/v2\/media?parent=55908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}